{"id":740,"date":"2026-04-16T19:32:53","date_gmt":"2026-04-16T17:32:53","guid":{"rendered":"https:\/\/useful-fictions-lab.fr\/?post_type=equipe&#038;p=740"},"modified":"2026-06-29T18:19:34","modified_gmt":"2026-06-29T16:19:34","slug":"sarah-bouttier","status":"publish","type":"equipe","link":"https:\/\/useful-fictions-lab.fr\/en\/equipe\/sarah-bouttier\/","title":{"rendered":"Sarah Bouttier"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-740","equipe","type-equipe","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/useful-fictions-lab.fr\/en\/wp-json\/wp\/v2\/equipe\/740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/useful-fictions-lab.fr\/en\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/useful-fictions-lab.fr\/en\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/useful-fictions-lab.fr\/en\/wp-json\/wp\/v2\/media?parent=740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}